{"id":4943,"date":"2013-11-09T08:00:59","date_gmt":"2013-11-09T07:00:59","guid":{"rendered":"https:\/\/www.saporideisassi.it\/blog\/?p=4943"},"modified":"2021-07-26T15:23:22","modified_gmt":"2021-07-26T13:23:22","slug":"mandorle-ricoperte-di-cioccolato-fondente-ricetta-semplice-ma-gustosa","status":"publish","type":"post","link":"https:\/\/www.saporideisassi.it\/blog\/mandorle-ricoperte-di-cioccolato-fondente-ricetta-semplice-ma-gustosa\/","title":{"rendered":"Mandorle ricoperte di Cioccolato Fondente, ricetta semplice ma gustosa"},"content":{"rendered":"<p><span style=\"color: #333333;\"><em>Scritto da <span style=\"text-decoration: underline;\">Angela<\/span><\/em><\/span><\/p>\n<p style=\"text-align: justify;\">L&#8217;estate proprio non vuole andare via, siamo a novembre e qui ci sono ancora 25\u00b0C e faccio davvero fatica a pensare che tra poco pi\u00f9 di un mese \u00e8 gi\u00e0 Natale! La mia mente ancora non riesce a pensare ai <a href=\" https:\/\/www.saporideisassi.it\/41-cesti-natalizi\"><strong>regali di Natale <\/strong><\/a>perch\u00e9 fuori \u00e8 ancora primavera! Ma manca davvero poco\u2026<\/p>\n<p style=\"text-align: justify;\">Ma se penso all&#8217;inverno, al Natale ed alle feste in generale, un prodotto che subito mi sale alla mente \u00e8, senza dubbio, il <strong>cioccolato<\/strong>. Per me non c&#8217;\u00e8 stagione per il cioccolato, lo mangerei anche con 45\u00b0C; ma una bella tavoletta di cioccolato puro, un fondente extra di almeno il 75% la vorrei gustare proprio in una serata fredda, davanti alla tv. L&#8217;Italia ha una lunga tradizione di cioccolato, ma sicuramente quello che preferisco in assoluto per le sue caratteristiche \u00e8 il <strong>Cioccolato di Modica<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Il <strong>Cioccolato di Modica<\/strong> nasce da una tradizione centenaria nell&#8217;omonima cittadina sicula ed \u00e8 oggi apprezzata in tutto il mondo per le sue caratteristiche peculiari. Quali sono le sue unicit\u00e0? Innanzitutto la <strong>quantit\u00e0<\/strong> e la <strong>qualit\u00e0 degli ingredienti<\/strong>: solo massa del <strong>miglior cacao<\/strong> e <strong>zucchero di canna da agricoltura biologica<\/strong>. Poi, la sua <strong>granulosit\u00e0<\/strong>, dovuta essenzialmente al metodo di produzione: la massa di cacao viene rigorosamente lavorata a mano e a bassa temperatura (siamo al di sotto dei 40\u00b0C) e ci\u00f2 non consente lo scioglimento dei granelli di zucchero di canna che, pertanto, rimangono integri. Aprendo una barretta di cioccolato di Modica noterete appunto questo interno &#8220;<strong>grezzo<\/strong>&#8221; e granuloso che lo rendono &#8220;<strong>croccante<\/strong>&#8221; ad ogni morso. Io semplicemente lo adoro! E da poche settimane \u00e8 anche possibile <strong>a<\/strong><strong>cquistare online differenti tipologie di <a href=\"https:\/\/www.saporideisassi.it\/64-cioccolato-artigianale\">cioccolato artigianale<\/a><\/strong> sul nostro store.<\/p>\n<p style=\"text-align: justify;\">Proprio pensando al cioccolato, ho pensato di proporvi una ricettina semplice semplice di un cioccolatino tradizionale della pasticceria pugliese e materana: le <strong>mandorle ricoperte di cioccolato<\/strong>.<br \/>\nPrepararli \u00e8 di una semplicit\u00e0 disarmante. Dovete solo stare attenti alla qualit\u00e0 del cioccolato fondente e, soprattutto alle mandorle per ottenere dolcetti di mandorle al cioccolato. In particolare, vi consiglio vivamente di utilizzare le<strong> mandorle italiane<\/strong>, meglio se le famose <strong>mandorle di Toritto<\/strong>, croccanti e saporite; non pensate neanche lontanamente di utilizzare le mandorle californiane perch\u00e9 sono talmente grosse e piene di olio che neanche dopo la tostatura diventano ben croccanti.<\/p>\n<p style=\"text-align: center;\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-4944 aligncenter\" title=\"Mandorle ricoperte di cioccolato\" src=\"https:\/\/www.saporideisassi.it\/blog\/wp-content\/uploads\/Mandorla1.jpg\" alt=\"Mandorle ricoperte di cioccolato\" width=\"603\" height=\"905\" srcset=\"https:\/\/www.saporideisassi.it\/blog\/wp-content\/uploads\/Mandorla1.jpg 670w, https:\/\/www.saporideisassi.it\/blog\/wp-content\/uploads\/Mandorla1-199x300.jpg 199w\" sizes=\"(max-width: 603px) 100vw, 603px\" \/><\/p>\n<p><strong>MANDORLE AL CIOCCOLATO RICETTA<\/strong><\/p>\n<p><span style=\"text-decoration: underline;\"><em>Ingredienti<\/em><\/span>: (per circa 40 cioccolatini)<\/p>\n<p>500 g di Cioccolato fondente 75%<br \/>\n600 g di mandorle di Toritto gi\u00e0 pelate<\/p>\n<p style=\"text-align: justify;\"><span style=\"text-decoration: underline;\"><em>Procedimento<\/em><\/span>:<\/p>\n<p>Tostate lievemente le mandorle in forno a 200\u00b0C per 5-6 minuti. Fatele raffreddare completamente.<br \/>\nPreparate una pentola con dell&#8217;acqua su cui potrete poggiare una ciotola di alluminio e mettete in quest&#8217;ultima il cioccolato fondente tagliato grossolanamente a pezzi<br \/>\nAccendete il fuoco e fate sciogliere il cioccolato a bagnomaria e, una volta liquefatto, versate le mandorle. Mescolate in modo tale che le mandorle si ricoprano completamente di cioccolato.<br \/>\nCon un cucchiaino prendete dalla ciotola delle mandorle con cioccolato e fatele scivolare negli appositi pirottini.<br \/>\nFate raffreddare completamente.<br \/>\nPossono essere conservati per diversi giorni nelle scatole di latta.<\/p>\n<p style=\"text-align: justify;\">Ps. Mia sorella sta girando con il vassoio\u2026chi ne vuole uno? ;)<\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-4950\" title=\"Mandorle ricoperte cioccolato fondente\" src=\"https:\/\/www.saporideisassi.it\/blog\/wp-content\/uploads\/Mandorla2.jpg\" alt=\"Mandorle ricoperte cioccolato fondente\" width=\"603\" height=\"905\" srcset=\"https:\/\/www.saporideisassi.it\/blog\/wp-content\/uploads\/Mandorla2.jpg 670w, https:\/\/www.saporideisassi.it\/blog\/wp-content\/uploads\/Mandorla2-199x300.jpg 199w\" sizes=\"(max-width: 603px) 100vw, 603px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Scritto da Angela L&#8217;estate proprio non vuole andare via, siamo a novembre e qui ci sono ancora 25\u00b0C e faccio davvero fatica a pensare che tra poco pi\u00f9 di un mese \u00e8 gi\u00e0 Natale! La mia mente ancora non riesce a pensare ai regali di Natale perch\u00e9 fuori \u00e8 ancora primavera! Ma manca davvero poco\u2026 [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":4952,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[3],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mandorle ricoperte di Cioccolato Fondente, ricetta semplice ma gustosa - Sapori dei Sassi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.saporideisassi.it\/blog\/mandorle-ricoperte-di-cioccolato-fondente-ricetta-semplice-ma-gustosa\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mandorle ricoperte di Cioccolato Fondente, ricetta semplice ma gustosa - Sapori dei Sassi\" \/>\n<meta property=\"og:description\" content=\"Scritto da Angela L&#8217;estate proprio non vuole andare via, siamo a novembre e qui ci sono ancora 25\u00b0C e faccio davvero fatica a pensare che tra poco pi\u00f9 di un mese \u00e8 gi\u00e0 Natale! La mia mente ancora non riesce a pensare ai regali di Natale perch\u00e9 fuori \u00e8 ancora primavera! Ma manca davvero poco\u2026 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.saporideisassi.it\/blog\/mandorle-ricoperte-di-cioccolato-fondente-ricetta-semplice-ma-gustosa\/\" \/>\n<meta property=\"og:site_name\" content=\"Sapori dei Sassi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/saporideisassi\/\" \/>\n<meta property=\"article:published_time\" content=\"2013-11-09T07:00:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-26T13:23:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.saporideisassi.it\/blog\/wp-content\/uploads\/Mandorla21.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"506\" \/>\n\t<meta property=\"og:image:height\" content=\"327\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Angela\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@saporideisassi\" \/>\n<meta name=\"twitter:site\" content=\"@saporideisassi\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Angela\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.saporideisassi.it\/blog\/mandorle-ricoperte-di-cioccolato-fondente-ricetta-semplice-ma-gustosa\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.saporideisassi.it\/blog\/mandorle-ricoperte-di-cioccolato-fondente-ricetta-semplice-ma-gustosa\/\"},\"author\":{\"name\":\"Angela\",\"@id\":\"https:\/\/www.saporideisassi.it\/blog\/#\/schema\/person\/ed88a50948d4f189a97db6147cd459fc\"},\"headline\":\"Mandorle ricoperte di Cioccolato Fondente, ricetta semplice ma gustosa\",\"datePublished\":\"2013-11-09T07:00:59+00:00\",\"dateModified\":\"2021-07-26T13:23:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.saporideisassi.it\/blog\/mandorle-ricoperte-di-cioccolato-fondente-ricetta-semplice-ma-gustosa\/\"},\"wordCount\":504,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.saporideisassi.it\/blog\/#organization\"},\"articleSection\":[\"Ricette\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.saporideisassi.it\/blog\/mandorle-ricoperte-di-cioccolato-fondente-ricetta-semplice-ma-gustosa\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.saporideisassi.it\/blog\/mandorle-ricoperte-di-cioccolato-fondente-ricetta-semplice-ma-gustosa\/\",\"url\":\"https:\/\/www.saporideisassi.it\/blog\/mandorle-ricoperte-di-cioccolato-fondente-ricetta-semplice-ma-gustosa\/\",\"name\":\"Mandorle ricoperte di Cioccolato Fondente, ricetta semplice ma gustosa - Sapori dei Sassi\",\"isPartOf\":{\"@id\":\"https:\/\/www.saporideisassi.it\/blog\/#website\"},\"datePublished\":\"2013-11-09T07:00:59+00:00\",\"dateModified\":\"2021-07-26T13:23:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.saporideisassi.it\/blog\/mandorle-ricoperte-di-cioccolato-fondente-ricetta-semplice-ma-gustosa\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.saporideisassi.it\/blog\/mandorle-ricoperte-di-cioccolato-fondente-ricetta-semplice-ma-gustosa\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.saporideisassi.it\/blog\/mandorle-ricoperte-di-cioccolato-fondente-ricetta-semplice-ma-gustosa\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.saporideisassi.it\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mandorle ricoperte di Cioccolato Fondente, ricetta semplice ma gustosa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.saporideisassi.it\/blog\/#website\",\"url\":\"https:\/\/www.saporideisassi.it\/blog\/\",\"name\":\"Sapori dei Sassi\",\"description\":\"Raccontiamo la cultura eno-gastronomica\",\"publisher\":{\"@id\":\"https:\/\/www.saporideisassi.it\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.saporideisassi.it\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.saporideisassi.it\/blog\/#organization\",\"name\":\"Sapori dei Sassi srl\",\"url\":\"https:\/\/www.saporideisassi.it\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.saporideisassi.it\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.saporideisassi.it\/blog\/wp-content\/uploads\/cropped-sapori-dei-sassi-logo-1622549037.png\",\"contentUrl\":\"https:\/\/www.saporideisassi.it\/blog\/wp-content\/uploads\/cropped-sapori-dei-sassi-logo-1622549037.png\",\"width\":213,\"height\":80,\"caption\":\"Sapori dei Sassi srl\"},\"image\":{\"@id\":\"https:\/\/www.saporideisassi.it\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/saporideisassi\/\",\"https:\/\/twitter.com\/saporideisassi\",\"https:\/\/www.instagram.com\/saporideisassi\/\",\"https:\/\/www.youtube.com\/user\/SaporideiSassi\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.saporideisassi.it\/blog\/#\/schema\/person\/ed88a50948d4f189a97db6147cd459fc\",\"name\":\"Angela\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.saporideisassi.it\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c6029fb253196a948a5e1ab99a205ac4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c6029fb253196a948a5e1ab99a205ac4?s=96&d=mm&r=g\",\"caption\":\"Angela\"},\"sameAs\":[\"https:\/\/www.saporideisassi.it\/blog\"],\"url\":\"https:\/\/www.saporideisassi.it\/blog\/author\/angela-b\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mandorle ricoperte di Cioccolato Fondente, ricetta semplice ma gustosa - Sapori dei Sassi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.saporideisassi.it\/blog\/mandorle-ricoperte-di-cioccolato-fondente-ricetta-semplice-ma-gustosa\/","og_locale":"it_IT","og_type":"article","og_title":"Mandorle ricoperte di Cioccolato Fondente, ricetta semplice ma gustosa - Sapori dei Sassi","og_description":"Scritto da Angela L&#8217;estate proprio non vuole andare via, siamo a novembre e qui ci sono ancora 25\u00b0C e faccio davvero fatica a pensare che tra poco pi\u00f9 di un mese \u00e8 gi\u00e0 Natale! La mia mente ancora non riesce a pensare ai regali di Natale perch\u00e9 fuori \u00e8 ancora primavera! Ma manca davvero poco\u2026 [&hellip;]","og_url":"https:\/\/www.saporideisassi.it\/blog\/mandorle-ricoperte-di-cioccolato-fondente-ricetta-semplice-ma-gustosa\/","og_site_name":"Sapori dei Sassi","article_publisher":"https:\/\/www.facebook.com\/saporideisassi\/","article_published_time":"2013-11-09T07:00:59+00:00","article_modified_time":"2021-07-26T13:23:22+00:00","og_image":[{"width":506,"height":327,"url":"https:\/\/www.saporideisassi.it\/blog\/wp-content\/uploads\/Mandorla21.jpg","type":"image\/jpeg"}],"author":"Angela","twitter_card":"summary_large_image","twitter_creator":"@saporideisassi","twitter_site":"@saporideisassi","twitter_misc":{"Scritto da":"Angela","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.saporideisassi.it\/blog\/mandorle-ricoperte-di-cioccolato-fondente-ricetta-semplice-ma-gustosa\/#article","isPartOf":{"@id":"https:\/\/www.saporideisassi.it\/blog\/mandorle-ricoperte-di-cioccolato-fondente-ricetta-semplice-ma-gustosa\/"},"author":{"name":"Angela","@id":"https:\/\/www.saporideisassi.it\/blog\/#\/schema\/person\/ed88a50948d4f189a97db6147cd459fc"},"headline":"Mandorle ricoperte di Cioccolato Fondente, ricetta semplice ma gustosa","datePublished":"2013-11-09T07:00:59+00:00","dateModified":"2021-07-26T13:23:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.saporideisassi.it\/blog\/mandorle-ricoperte-di-cioccolato-fondente-ricetta-semplice-ma-gustosa\/"},"wordCount":504,"commentCount":0,"publisher":{"@id":"https:\/\/www.saporideisassi.it\/blog\/#organization"},"articleSection":["Ricette"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.saporideisassi.it\/blog\/mandorle-ricoperte-di-cioccolato-fondente-ricetta-semplice-ma-gustosa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.saporideisassi.it\/blog\/mandorle-ricoperte-di-cioccolato-fondente-ricetta-semplice-ma-gustosa\/","url":"https:\/\/www.saporideisassi.it\/blog\/mandorle-ricoperte-di-cioccolato-fondente-ricetta-semplice-ma-gustosa\/","name":"Mandorle ricoperte di Cioccolato Fondente, ricetta semplice ma gustosa - Sapori dei Sassi","isPartOf":{"@id":"https:\/\/www.saporideisassi.it\/blog\/#website"},"datePublished":"2013-11-09T07:00:59+00:00","dateModified":"2021-07-26T13:23:22+00:00","breadcrumb":{"@id":"https:\/\/www.saporideisassi.it\/blog\/mandorle-ricoperte-di-cioccolato-fondente-ricetta-semplice-ma-gustosa\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.saporideisassi.it\/blog\/mandorle-ricoperte-di-cioccolato-fondente-ricetta-semplice-ma-gustosa\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.saporideisassi.it\/blog\/mandorle-ricoperte-di-cioccolato-fondente-ricetta-semplice-ma-gustosa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.saporideisassi.it\/blog\/"},{"@type":"ListItem","position":2,"name":"Mandorle ricoperte di Cioccolato Fondente, ricetta semplice ma gustosa"}]},{"@type":"WebSite","@id":"https:\/\/www.saporideisassi.it\/blog\/#website","url":"https:\/\/www.saporideisassi.it\/blog\/","name":"Sapori dei Sassi","description":"Raccontiamo la cultura eno-gastronomica","publisher":{"@id":"https:\/\/www.saporideisassi.it\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.saporideisassi.it\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.saporideisassi.it\/blog\/#organization","name":"Sapori dei Sassi srl","url":"https:\/\/www.saporideisassi.it\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.saporideisassi.it\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.saporideisassi.it\/blog\/wp-content\/uploads\/cropped-sapori-dei-sassi-logo-1622549037.png","contentUrl":"https:\/\/www.saporideisassi.it\/blog\/wp-content\/uploads\/cropped-sapori-dei-sassi-logo-1622549037.png","width":213,"height":80,"caption":"Sapori dei Sassi srl"},"image":{"@id":"https:\/\/www.saporideisassi.it\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/saporideisassi\/","https:\/\/twitter.com\/saporideisassi","https:\/\/www.instagram.com\/saporideisassi\/","https:\/\/www.youtube.com\/user\/SaporideiSassi"]},{"@type":"Person","@id":"https:\/\/www.saporideisassi.it\/blog\/#\/schema\/person\/ed88a50948d4f189a97db6147cd459fc","name":"Angela","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.saporideisassi.it\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c6029fb253196a948a5e1ab99a205ac4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c6029fb253196a948a5e1ab99a205ac4?s=96&d=mm&r=g","caption":"Angela"},"sameAs":["https:\/\/www.saporideisassi.it\/blog"],"url":"https:\/\/www.saporideisassi.it\/blog\/author\/angela-b\/"}]}},"modified_by":"Giuseppe","_links":{"self":[{"href":"https:\/\/www.saporideisassi.it\/blog\/wp-json\/wp\/v2\/posts\/4943"}],"collection":[{"href":"https:\/\/www.saporideisassi.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.saporideisassi.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.saporideisassi.it\/blog\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.saporideisassi.it\/blog\/wp-json\/wp\/v2\/comments?post=4943"}],"version-history":[{"count":2,"href":"https:\/\/www.saporideisassi.it\/blog\/wp-json\/wp\/v2\/posts\/4943\/revisions"}],"predecessor-version":[{"id":10392,"href":"https:\/\/www.saporideisassi.it\/blog\/wp-json\/wp\/v2\/posts\/4943\/revisions\/10392"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.saporideisassi.it\/blog\/wp-json\/wp\/v2\/media\/4952"}],"wp:attachment":[{"href":"https:\/\/www.saporideisassi.it\/blog\/wp-json\/wp\/v2\/media?parent=4943"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.saporideisassi.it\/blog\/wp-json\/wp\/v2\/categories?post=4943"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.saporideisassi.it\/blog\/wp-json\/wp\/v2\/tags?post=4943"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}